{"id":970,"count":1,"description":"","link":"https:\/\/alicezumbe.de\/blog\/tag\/presseartikel\/","name":"Presseartikel","slug":"presseartikel","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/tags\/970"}],"collection":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/posts?tags=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}