{"id":3358,"date":"2018-04-26T17:44:42","date_gmt":"2018-04-26T15:44:42","guid":{"rendered":"http:\/\/alicezumbe.de\/blog\/?p=3358"},"modified":"2018-04-26T21:19:33","modified_gmt":"2018-04-26T19:19:33","slug":"kolumne-zeitreise-und-bekenntnisse","status":"publish","type":"post","link":"https:\/\/alicezumbe.de\/blog\/kolumne-zeitreise-und-bekenntnisse\/","title":{"rendered":"Kolumne: Zeitreise &#038; Bekenntnisse."},"content":{"rendered":"<figure id=\"attachment_3359\" aria-labelledby=\"figcaption_attachment_3359\" class=\"wp-caption aligncenter\" style=\"width: 160px\"><a href=\"http:\/\/alicezumbe.de\/blog\/kolumne-zeitreise-und-bekenntnisse\/alice_zumbe_nb-102\/\" rel=\"attachment wp-att-3359\"><img decoding=\"async\" loading=\"lazy\" class=\"size-thumbnail wp-image-3359\" title=\"Alice_Zumb\u00e9\" src=\"http:\/\/alicezumbe.de\/blog\/blogin\/media\/\/2018\/04\/Alice_Zumbe_nb1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"figcaption_attachment_3359\" class=\"wp-caption-text\">Liebesbriefe von Alice.<\/figcaption><\/figure>\n<address style=\"text-align: center;\">&#8222;Der Wochenr\u00fcckblick \u00fcber Themen, die Alice bewegten.<\/address>\n<address style=\"text-align: center;\">Immer in Verbindung mit Liebe.&#8220;<\/address>\n<p>&#8222;Lieber Freund,<\/p>\n<p>vor drei Tagen traf ich nacheinander auf eine Dame mit Herrn und einen weiteren Herrn, der mir aus vergangenen Tagen wohl bekannt ist. Mit ersteren verband mich an diesem f\u00fcr mich sehr bedeutsamen <em>Aloha Monday<\/em> ein zauberhaftes Parkbank-Gespr\u00e4ch an der k\u00f6niglichen Allee, das nach und nach ihre gemeinsam erlebten Geschichten der Vergangenheit offenbarte, die mit einem Bekenntnis f\u00fcreinander begannen. Vor weit \u00fcber 60 Jahren versprachen sich die beiden eine gemeinsame Zukunft, die in Berlin begann und schmiedeten sogleich Pl\u00e4ne daf\u00fcr. Sie untermauerten ihre Liebe zueinander mit Eckpfeilern, die sie gemeinsam bauen wollten. R\u00fcckblickend haben sie es geschafft ihr Lebenswerk weitestgehends zu vollenden: sie sind ihrem Bekenntnis treu geblieben, haben zwei Mal neues Leben geschenkt und die Herausforderungen des Lebens gemeinsam gemeistert. Zufriedenheit und Liebe entdeckte ich in beider Anlitz und den Genuss des Lebens, das Hier und Jetzt, das ihnen auch die Fr\u00fcchte ihres Lebens reichte. So freute ich mich \u00fcber unseren erf\u00fcllenden Gedankenaustausch und mit vom Herzen gefassten H\u00e4ndesch\u00fctteln verabschiedeten wir uns schlie\u00dflich voneinander. Mit dem ausgesprochenen Gl\u00fcck f\u00fcr jeden auf seinem Weg brachte mich mein Drahtesel dem ersten Kaffee des Tages ein St\u00fcck n\u00e4her. Nichts ahnend lief dort dann der Brite und alte Seeb\u00e4r am Caf\u00e9 vorbei, den ich seit drei Jahren nicht mehr getroffen hatte. Voller Freude verbrachten wir nun wieder gemeinsam etwas Zeit miteinander, erz\u00e4hlten von den Erlebnissen der j\u00fcngsten Vergangenheit und so erfuhr ich auch von seinem Bekenntnis vor 40 Jahren, das sich bald j\u00e4hrte. Im Kreise seiner beiden T\u00f6chter wird er den Jahrestag mit seiner Herzensdame geb\u00fchrend zelebrieren und mit der Aussicht auf ein erneutes Zusammentreffen zum Kaffee verabschiedete ich mich schlie\u00dflich auch von dem wei\u00dfb\u00e4rtigen Herrn, der einst die Weltmeere bereiste.<\/p>\n<p>Ein Bekenntnis anderer Art und doch voller Vertrauen und Liebe gefasst, untermauerte ich dann an diesem denkw\u00fcrdigen Montag, indem ich auf den <em>&#8222;Freischalten&#8220;<\/em>-Button f\u00fcr unsere <em>Bridge to Hawaii<\/em> <a title=\"Bridge to Hawaii Crowdfunding bei Kickstarter\" href=\"https:\/\/www.kickstarter.com\/projects\/alicezumbe\/bridge-to-hawaii?ref=nav_search&amp;result=project&amp;term=bridge\" target=\"_blank\">Crowdfunding Kampagne<\/a> in der virtuellen Welt dr\u00fcckte. Mein Bekenntnis gegen\u00fcber der gesamten Crew lautete, dass ich einen Weg finden werde unser Projekt zu realisieren und dies nun eine M\u00f6glichkeit dazu offenbart. Somit darf ich Dir an dieser Stelle tief bewegt und voller Freude mitteilen, dass wir online gegangen sind. M\u00f6glichst viele Menschen m\u00f6chten wir \u00fcber diesen Weg erreichen, mit ihnen unsere Visionen, unseren Traum teilen und schlie\u00dflich gemeinsam die Mittel aufbringen, die notwendig sind, um dies alles zu erf\u00fcllen. Begleitet wurde dieser Tag dann f\u00fcr mich im wahrsten Sinne vom Aloha, das auch f\u00fcr Liebe steht, denn es spiegelte sich in den Begegnungen und begann mit dem Wind. So zeigte mein geliebter Wegweiser, das Segelschiff in luftiger H\u00f6he, die Richtung Ost\/Nordost an und wehte so den Aloha-Ruf direkt von Hawaii her\u00fcber. Prombt kreuzte dann noch unerwartet ein <em>Bridge to Hawaii<\/em> Crew Mitglied meinen Weg und der junge Mann mit den Rasta-Z\u00f6pfen leistete mir auf einer Bank an einem Brunnen eine Zeit lang Gesellschaft.<\/p>\n<p>Bewegte Zeiten der letzten zwei Wochen liegen nun hinter mir, die manchmal fast unglaubliches zu Tage brachten und so meine Seele ab und an regelrecht \u00fcbersprudeln lie\u00dfen oder es immer noch tun. So flossen auch Tr\u00e4nen, doch nicht der Trauer, sondern der Freude und des zutiefst Ber\u00fchrtseins und als ob der Himmel in diesen Gesang mit einstimmen wollte, \u00f6ffnete auch er am letzten Sonntag seine Tore und lie\u00df das Wasser des Lebens auf die Erde prasseln, die gerade so wundersch\u00f6n erbl\u00fcht. Im Volksgarten, einer Oase der Stadt, wohnte ich dann diesem Naturschauspiel bei und lauschte eine Weile dem Regen, besch\u00fctzt unter Bl\u00e4tterwerk. Ganze drei Tage zuvor nahm ich mir in dieser gr\u00fcnen Lunge eine Auszeit von den Besch\u00e4ftigungen rund um <em>Bridge to Hawaii<\/em> und genoss in vollen Z\u00fcgen den Fr\u00fchling um mich herum. Manchmal lie\u00dfen mich die visuellen Eindr\u00fccke fast sprachlos zur\u00fcck, so wundersch\u00f6n pr\u00e4sentierte sich die Natur in der Erkenntnis ein Teil ihrer und dankbar f\u00fcr den Moment zu sein. In der Mitte meiner Selbst setzte sich dann noch ein Herr zu mir auf die Parkbank im Schatten mit Blick auf den See und das gegen\u00fcberliegende Bootshaus. Es folgte ein sch\u00f6ner Gedankenaustausch und ein Moment der telefonischen Unterbrechung, der mir ein L\u00e4cheln auf das Gesicht zauberte, da ich Zeuge der liebevollen Worte an die Herzensdame wurde. Der Herr schenkte mir wiederum sein Ohr auf Zeit und entschwand schlie\u00dflich in seinen wohlverdienten Feierabend.<\/p>\n<p>Knapp eine Woche zuvor hatte mein Herz eine Dame ber\u00fchrt, zu der mich Amtsangelegenheiten gef\u00fchrt hatten. Mit regem Interesse folgte auch sie meinen Ausf\u00fchrungen \u00fcber die neuesten Entwicklungen zu <em>Bridge to Hawaii<\/em> und voller Freude konnte ich ihr damals schon den fertig geschnittenen Pitch-Film zeigen, den die Crew gemeinsam auf die Beine gestellte hatte. Ihre Anerkennung dr\u00fcckte sich neben dem Strahlen in ihren Augen, dann auch in einer monet\u00e4ren Spende aus, die sie vorbehaltlos und mit Freude mir entgegenreichte. Diese landete dann zun\u00e4chst in unser noch unbemaltes <em>Hawaii-Schweinerl<\/em> und letzten Montag dann als erster Finanzierungsbetrag auf der Crowdfunding Plattform, wo danach die wunderbaren Worte <em>&#8222;Dank deines Beitrags ist Bridge to Hawaii seiner Verwirklichung einen Schritt n\u00e4her.&#8220;<\/em> zu lesen waren. Bewegende Momente, die sich auch am n\u00e4chsten Tag fortsetzten. Mit dem Ansinnen an diesem Samstag vor 11 Tagen die Seele baumeln zu lassen bestieg ich meinen Drahtesel und entschied mich auf dem Weg spontan einen Abstecher zum jungen Mann mit dem <em>Aloha<\/em>-Spirit zu unternehmen. Mit Freude erkannte ich dann schon vom Weiten den Weihnachtsmann, der auf der Terrasse des Caf\u00e9s sa\u00df und alsbald lagen wir uns zur Begr\u00fc\u00dfung \u00fcber dieses unverhoffte Gl\u00fcck in den Armen. Sonnenbeschienen genossen wir die Anwesenheit des anderen und als er kurz im Inneren verschwand, entdeckte ich noch in einem der gegen\u00fcberliegenden Fenster ein Schild, auf dem in gro\u00dfen Lettern<em> &#8222;Peace &amp; Love&#8220;<\/em> geschrieben stand: <em>spooky<\/em>.<\/p>\n<p>Der betagte Herr mit dem wei\u00dfen Haar verabschiedete sich und dem jungen Mann mit <em>Aloha<\/em>-Spirit legte ich den Pitch-Film in die H\u00e4nde, den er noch nicht kannte. Nach meinem Besuch des stillen \u00d6rtchens trat mir dann das j\u00fcngste Crew Mitglied entgegen und bekundete bewegt mit einem Glitzern in den Augen: <em>&#8222;Der ist super sch\u00f6n geworden.&#8220;<\/em>. Ein paar Tage sp\u00e4ter lie\u00df mich dann auch seine zauberhafte Schwester mit den polynesischen Wurzeln wissen, wie ber\u00fchrt sie vom filmischen Werk ist und es sogleich mit ihren Verwandten auf Hawaii in der virtuellen Welt teilte. Ihr Bruderherz ber\u00fchrte dann noch meines, als er mir erz\u00e4hlte, dass er die Frage nach dem <em>&#8222;Warum?&#8220;<\/em> mit <em>&#8222;Alice glaubt einfach daran.&#8220;<\/em> beantwortete und mir so aus der Seele sprach. Der Weg zur\u00fcck in den Kiez f\u00fchrte dann auf die Terrasse des <em>Covent Garden<\/em>, auf der mich wenig sp\u00e4ter im Sonnenschein ein weiterer <em>spooky<\/em>-Moment erreichte. Eine Dame ver\u00f6ffentlichte in der virtuellen Welt ein Foto vom <em>Waikiki Beach<\/em> in Honolulu, auf dem ein <em>&#8222;Lifeguard&#8220;<\/em>-Turm zu sehen war. In gro\u00dfen, roten Lettern war er mit <em>&#8222;2H&#8220;<\/em> beschriftet und erinnerte mich sofort mit einem imagin\u00e4ren <em>&#8222;B&#8220;<\/em> davor an unser <em>Bridge to Hawaii<\/em>-K\u00fcrzel. F\u00fcr mich ein Wegweiser, der mich zum Strahlen brachte und ich das Foto weiter teilte.<\/p>\n<p>Auch der folgende Sonntag versprach schon zu Beginn bewegende Zeiten, denn die Schmetterlingsdame war aus ihrer neuen Heimat eingeflogen und brachte f\u00fcr den Nachmittag ausreichend Zeit f\u00fcr gemeinsame Stunden mit. Nach der Wiedersehensfreude schloss sich ihr noch der Arzt aus Nordafrika \u00fcberraschend an, der seinen Ehrentag mit uns verbrachte und der junge Mann aus der WG, der ebenfalls den Weg zu uns fand. So vergingen angenehme Stunden mit hawaiianischem Geburtagsst\u00e4ndchen und einem Spaziergang zum Fluss, bis die Dame wieder den Flieger in Richtung S\u00fcden erreichen musste.<\/p>\n<p>Die n\u00e4chsten Tage standen dann ganz im Zeichen von <em>Bridge to Hawaii<\/em> mit den notwendigen Vorbereitungen zur Crowdfunding Kampagne von Fr\u00fch bis um Mitternacht und nur kurz unterbrochen vom Sommer-<em>feeling<\/em> und Wasserspielen in der Innenstadt, ein wenig Park-Liebe beim hindurchfahren und viel Geduld bei technischen Herausforderungen. Letzte Woche Freitag konnte ich dann \u00fcbergl\u00fccklich und umrahmt von wunderbaren Menschen an diesem Tag, der gesamten Crew die Neuigkeiten zur Fertigstellung mitteilen. Mit Blume im Haar und in Begleitung der doppelnamigen Dame, folgten wir dann am Samstag dem Flusslauf und dem <em>Aloha<\/em>-Ruf eines Herrn, der zur Er\u00f6ffnung seines <em>Poke<\/em>-Imbiss auf einem Schiff am Fluss geladen hatte. Vor Ort waren die Vorbereitungen noch nicht g\u00e4nzlich abgeschlossen und so blieb es f\u00fcr uns erst einmal bei der Bewunderung der Location, einem <em>Aloha<\/em>-Gru\u00df f\u00fcr den Gastgeber mit \u00dcberreichung eines Lei und dem Blick auf kulinarisches, das an das hawaiianische Nationalgericht angelegt ist. Am Nachmittag erreichte mich dann die Nachricht eines ehemaligen Schulkameraden, der mich vor wenigen Jahren in der virtuellen Welt fand und Kontakt aufgenommen hatte. Nun lie\u00df er mich wissen, dass er zum angek\u00fcndigten Jahrgangstreffen am Zielort angekommen war und ich gerne vorbeikommen k\u00f6nnte. So folgte ich auch diesem Ruf auf die andere Flussseite, ohne zu ahnen was mich dort au\u00dfer Charly erwartete, denn das Jahrgangstreffen verband ich zun\u00e4chst nicht mit meiner Person.<\/p>\n<p>Mit der Freude \u00fcber den Weg entlang eines Kanals bei herrlichem Fr\u00fchlingswetter, den ich das letzte Mal in meiner Schulzeit befahren hatte, erreichte ich schlie\u00dflich das Lokal mit angrenzendem Biergarten, der sich vom weiten schon gut gef\u00fcllt zeigte. Ab diesem Moment ereignete sich fast unglaubliches und in den kommenden vier Stunden sprudelte nicht nur einmal das Wort <em>&#8222;surreal&#8220;<\/em> aus meinem Mund heraus. V\u00f6llig unerwartet war ich beim Betreten des Biergartens in eine Zeitmaschine eingestiegen und \u00fcber drei Jahrzehnte in die Vergangenheit zur\u00fcckgereist. Genauso f\u00fchlte es sich in jedem Fall an, als ich nach und nach die Gesichter der Menschen um mich herum betrachtete und meine Synapsen unentwegt alte Verbindungen zu gemeinsamen Geschichten blitzartig wieder aufleben lie\u00dfen. Gef\u00fchlt unz\u00e4hlige Sinneseindr\u00fccke hielten fortan meinen Dopamin-Spiegel im Blut \u00fcber die Ma\u00dfen aufrecht und so erfreute ich mich an dem Sichtbaren genauso wie an den Gespr\u00e4chen, die sich im Laufe des Abends entwickelten. Denn kaum einer der zahlreichen Anwesenden blieb mir g\u00e4nzlich unbekannt, verbanden uns doch gemeinsame Schuljahre und ebenso zahlreiche gemeinsame Erlebnisse. Zun\u00e4chst entdeckte ich Charly, dem ich schlie\u00dflich dieses wunderbare Geschenk der Begegnungen verdanke. Als w\u00e4re die Zeit dazwischen stehengeblieben, sah ich den jungen Kerl in ihm, der einst Zeit im Kunst-Leistungskurs mit mir teilte und sein Talent heutzutage wieder aufleben l\u00e4sst. Unverkennbar auch an den Bemalungen seiner Haut zu sehen. Anregend gestaltete sich unsere Unterhaltung, der sich bald eine Dame anschloss, die ich zu den wenigen Unbekannten z\u00e4hlte. Ganz im Gegensatz zu Sandra, die ich am Nebentisch bereits zu Beginn wahrnahm, auch weil sie mich entdeckte und meinen Namen rief. Wunderbare Zeiten verbrachten wir damals zusammen und ich erinnere mich gerne an ihr Zuhause mit Irish Setter und Familie. Meinen 16ten Geburtstag feierten wir gemeinsam in einem damals angesagten Lokal und l\u00e4uteten damit meine Ausgeh-Zeit ein. Nun fielen wir uns erstmals wieder herzlich in die Arme und wechselten \u00fcber den Abend hinweg das ein oder andere Wort. Sie half mir dann namentlich bei einem Herrn aus, den ich wiedererkannte, allerdings noch nicht wirklich zuordnen konnte. Marcel zeichnete sich an diesem Abend vor allem durch seine sch\u00f6nen Komplimente aus, die er zum Ausdruck brachte. So vernahm ich, dass ich ihn wohl damals mit meiner Pers\u00f6nlichkeit nachhaltig beeindruckt hatte und Alessandro lie\u00df er wissen, wie beeindruckt er von der Sprachgewandheit des Italieners gewesen war und dieser f\u00fcr ihn eine Bereicherung darstellte, was mich wiederum beeindruckte. Letztlich standen wir wohl gemeinsam auf den B\u00fchnenbrettern, die f\u00fcr manchen die Welt bedeuten, als wir beide uns in der Theater AG erprobten. An Brigitte erinnerte ich mich sofort, hatte ich sie doch vor Jahren auf dem Bildschirm entdeckt und damals noch erfolglos versucht Kontakt \u00fcber ihre Agentur aufzunehmen. Dass die Dinge sich dann doch finden, bewies sich an diesem Abend, der uns f\u00fcr den Augenblick zueinanderf\u00fchrte. Silkes Gesicht kam mir sofort wieder in den Sinn und ihre fr\u00f6hliche Art entlockte mir auch im Waschraum noch ein L\u00e4cheln um die Mundwinkel. Genaueres konnte ich dann nicht ergr\u00fcnden. Der Hinweis auf einen Herrn an dem langen Holztisch, der in meine Richtung schaute und damals aus Ghana zu uns in die Schule gekommen war, entlockte mir sofort einen begeisterten Ausruf. Bald wechselten auch Oliver und ich Worte der Freude \u00fcber das Wiedersehen miteinander und so lie\u00df ich ihn auch wissen, dass ich nie vergessen w\u00fcrde wie er mir die englische Sprache ein bisschen n\u00e4her brachte. <em>&#8222;Which kind of wall&#8230;&#8220;<\/em> hei\u00dft es seitdem f\u00fcr mich richtig, dank seines Hinweis. Das Lachen war an diesem Abend nicht nur mein st\u00e4ndiger Begleiter und so danke ich auch von Herzen den Begegnungen mit Barbara in dem farbenfrohen Kleid, Roland, der wohl das organisatorische \u00fcbernommen hatte, Melita, die wohl damals dunkle Haare trug, Sandra, die zweite im Bunde der Namensgleichen, Ingo, der Herr mit ergrautem Haar, dessen Wege meine vor einigen Jahren schon mal kreuzten, Altan, den ich sofort erkannte, Volker, der etwas offenes in seinen Augen durchscheinen lie\u00df, Kirsten, die unter anderem vom <em>&#8222;sich selbst finden&#8220;<\/em> sprach, und, und, und&#8230; alle, die ich sah strahlten von innen heraus und verspr\u00fchten Herzlichkeit und Energie unter freiem Himmel. Fast berauscht von den Erlebnissen des Abends verlie\u00df ich schlie\u00dflich nach einer Verabschiedungsrunde diese Gesellschaft und trat mit meinem Drahtesel den Heimweg an. Ersch\u00f6pft und gl\u00fccklich endete dann dieser Tag f\u00fcr mich voller Dankbarkeit.<\/p>\n<p>Am Dienstagnachmittag traf ich dann wieder einmal auf meine betagte Brieffreundin, die ich seit Ostern nicht mehr gesehen hatte und im Anschluss daran besuchte ich nochmals den jungen Mann mit <em>Aloha<\/em>-Spirit, um unerwartet ein bisschen Gl\u00fccksstaub f\u00fcr verlorengegangenes zu verteilen und von <em>Bridge to Hawaii<\/em>-Neuigkeiten zu berichten, bis auch dieser Ausflug irgendwann wieder zu Hause endete. Bewegende Zeiten liegen hinter mir. Was morgen wird, liegt noch in der Glaskugel der Zukunft verborgen und doch ist gewiss, dass sich vieles um <em>Bridge to Hawaii<\/em> drehen wird. Ein spannendes Abenteuer, wie ich es mir gew\u00fcnscht habe und ein Traum, an dem nun schon mehr Menschen glauben. So darf es weitergehen, denn es sind doch die Tr\u00e4ume, die jeden von uns motivieren voran zu gehen und an sich selbst zu glauben. Aufgeben ist schlie\u00dflich keine Option. In diesem Sinne danke ich auch Dir f\u00fcr Deine Unterst\u00fctzung und sage <em>&#8222;bis bald&#8220;<\/em>.<\/p>\n<p>In Liebe mit Aloha,<\/p>\n<p>Alice<\/p>\n<p>PS. Vor ein paar Tagen wohnte ich einer <em>Live<\/em>-Schaltung des Dalai Lama in Dharamsala vor hunderten Menschen bei, dessen folgende Worte ich Dir an dieser Stelle noch nahe bringen m\u00f6chte.<\/p>\n<p style=\"text-align: center;\"><em>&#8222;The more you are motivated by LOVE<br \/>\nthe more fearless and FREE your action will be.&#8220;<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Der Wochenr\u00fcckblick \u00fcber Themen, die Alice bewegten. Immer in Verbindung mit Liebe.&#8220; &#8222;Lieber Freund, vor drei Tagen traf ich nacheinander auf eine Dame mit Herrn und einen weiteren Herrn, der mir aus vergangenen Tagen wohl bekannt ist. Mit ersteren verband &hellip; <a href=\"https:\/\/alicezumbe.de\/blog\/kolumne-zeitreise-und-bekenntnisse\/\">Lesen fortsetzen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[138,820,289,841,634,825,644,842,206,98,333,314,143,266,388],"_links":{"self":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/posts\/3358"}],"collection":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/comments?post=3358"}],"version-history":[{"count":20,"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/posts\/3358\/revisions"}],"predecessor-version":[{"id":3377,"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/posts\/3358\/revisions\/3377"}],"wp:attachment":[{"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/media?parent=3358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/categories?post=3358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alicezumbe.de\/blog\/wp-json\/wp\/v2\/tags?post=3358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}